{"id":1818,"date":"2019-02-01T04:49:48","date_gmt":"2019-02-01T04:49:48","guid":{"rendered":"https:\/\/pimentoteca.com.br\/blog\/?p=1818"},"modified":"2026-07-13T20:29:11","modified_gmt":"2026-07-13T23:29:11","slug":"como-neutralizar-pimenta","status":"publish","type":"post","link":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/","title":{"rendered":"Como neutralizar pimenta ap\u00f3s seu consumo?"},"content":{"rendered":"<p>Quer saber <strong>como neutralizar pimenta<\/strong> ap\u00f3s consumi-la? Se voc\u00ea j\u00e1 passou pela situa\u00e7\u00e3o de comer uma pimenta e arder mais do que o esperado, aprenda o que fazer nestes casos.<\/p>\n<h2 class=\"wp-block-heading\">Minha boca est\u00e1 em chamas! O que fazer?<\/h2>\n<p>Todas as pimentas que est\u00e3o na categoria nucleares (as pimentas mais ardidas do mundo) tem a caracter\u00edstica de arder por pelo menos 20 minutos. Isso se a quantidade consumida for significante (pelo menos uma fatia da pimenta in natura). <\/p>\n<p>Parece brincadeira, mas n\u00e3o \u00e9! Essas pimentas podem arder por muito tempo. Isso costuma deixar as pessoas desesperadas quando s\u00e3o pegas desprevenidas por esse ardor. <\/p>\n<p>N\u00f3s j\u00e1 experimentamos v\u00e1rios tipos de solu\u00e7\u00f5es para neutralizar a ard\u00eancia. <\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=hotviagens-20&amp;marketplace=amazon&amp;region=BR&amp;placement=B07XH4C2KT&amp;asins=B07XH4C2KT&amp;linkId=565e7220df94f8a0a7d54944b73c2114&amp;show_border=true&amp;link_opens_in_new_window=true\"><\/iframe><\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=hotviagens-20&amp;marketplace=amazon&amp;region=BR&amp;placement=B07K8SBKFK&amp;asins=B07K8SBKFK&amp;linkId=71c5523020edcaf2e2c1a2ccca372712&amp;show_border=true&amp;link_opens_in_new_window=true\"><\/iframe><\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=hotviagens-20&amp;marketplace=amazon&amp;region=BR&amp;placement=B07MZ98MXP&amp;asins=B07MZ98MXP&amp;linkId=03ef18a6dbbee5f538d4842224e06113&amp;show_border=true&amp;link_opens_in_new_window=true\"><\/iframe><\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=hotviagens-20&amp;marketplace=amazon&amp;region=BR&amp;placement=B076H8V8VF&amp;asins=B076H8V8VF&amp;linkId=75d69548d6d643d7160b0b0b86cc4033&amp;show_border=true&amp;link_opens_in_new_window=true\"><\/iframe><\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=hotviagens-20&amp;marketplace=amazon&amp;region=BR&amp;placement=B085VW7BVK&amp;asins=B085VW7BVK&amp;linkId=303597346d181d4989231db7a43ba920&amp;show_border=true&amp;link_opens_in_new_window=true\"><\/iframe><\/p>\n<p><iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/ws-na.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&amp;OneJS=1&amp;Operation=GetAdHtml&amp;MarketPlace=BR&amp;source=ss&amp;ref=as_ss_li_til&amp;ad_type=product_link&amp;tracking_id=hotviagens-20&amp;marketplace=amazon&amp;region=BR&amp;placement=B076X6WRN9&amp;asins=B076X6WRN9&amp;linkId=2a74d17a5c940d3a9d41933a186c528b&amp;show_border=true&amp;link_opens_in_new_window=true\"><\/iframe><\/p>\n<p>A solu\u00e7\u00e3o mais eficiente, sem sombra de d\u00favidas, \u00e9 utilizar <strong>pedras de gelo.<\/strong> Pode parecer besteira, mas o gelo consegue deixar sua l\u00edngua adormecida e com isso voc\u00ea n\u00e3o vai sentir mais o ardor. Por\u00e9m, \u00e9 importante ressaltar que voc\u00ea precisa ficar com o gelo na boca at\u00e9 derreter. Caso contr\u00e1rio, o ardor ir\u00e1 voltar na hora.<\/p>\n<h3 class=\"wp-block-heading\">Confira o que utilizar (ou n\u00e3o) para neutralizar pimenta:<\/h3>\n<p>Como citamos acima, o gelo \u00e9 a melhor op\u00e7\u00e3o de como neutralizar pimenta. Al\u00e9m de reidratar, vai zerar o desconforto moment\u00e2neo gerado pela pimenta.<\/p>\n<p>A seguir mais alguns exemplos abaixo:<\/p>\n<p>&#8211; Qualquer produto com gordura tamb\u00e9m vai ajudar, como por exemplo leite, manteiga, requeij\u00e3o, etc. Nesses casos o ardor ir\u00e1 diminuir, mas n\u00e3o vai desaparecer.<br \/>&#8211; \u00c1gua, refrigerantes e outras bebidas s\u00f3 dar\u00e3o a sensa\u00e7\u00e3o de melhora temporariamente, mas na verdade v\u00e3o espalhar o ardor por toda a boca.<br \/>&#8211; Nunca consuma nada quente! Isso porque qualquer coisa aquecida vai potencializar o efeito da ard\u00eancia.<\/p>\n<p>Quer entender mais sobre pimentas? <a href=\"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/escala-scoville\/\">Veja aqui uma rela\u00e7\u00e3o das pimentas mais fortes do mundo!<\/a><\/p>\n<p><!--zm-leia-tambem--><\/p>\n<h2>Leia tamb\u00e9m<\/h2>\n<ul>\n<li><a href=\"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/viciados-em-pimenta\/\">Viciados em Pimenta: Descubra Seus Segredos<\/a><\/li>\n<li><a href=\"https:\/\/pimentoteca.com.br\/blog\/experimente\/pimenta-rosa-beneficios\/\">Pimenta Rosa Benef\u00edcios: Descubra Como Transformar Sua Sa\u00fade<\/a><\/li>\n<li><a href=\"https:\/\/pimentoteca.com.br\/blog\/experimente\/carolina-reaper-chocolate\/\">Carolina Reaper Chocolate: Guia Para Amantes de Pimenta<\/a><\/li>\n<\/ul>\n<p>Quer levar o mundo das pimentas pra sua cozinha? Conhe\u00e7a os produtos da <a href=\"https:\/\/pimentoteca.com.br\/\">loja da Pimentoteca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer saber como neutralizar pimenta ap\u00f3s consumi-la? Se voc\u00ea j\u00e1 passou pela situa\u00e7\u00e3o de comer uma pimenta e arder mais do que o esperado, aprenda o que fazer nestes casos. Minha boca est\u00e1 em chamas! O que fazer? Todas as pimentas que est\u00e3o na categoria nucleares (as pimentas mais ardidas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[83,98,95,97,52,51,10,96],"class_list":["post-1818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-ardencia","tag-chamas","tag-como-neutralizar","tag-gelo","tag-leite","tag-manteiga","tag-pimenta","tag-requeijao"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[3],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como neutralizar pimenta ap\u00f3s seu consumo? - Pimentoteca<\/title>\n<meta name=\"description\" content=\"Sua boca est\u00e1 em chamas? N\u00e3o sabe o que fazer? Quer descobrir como neutralizar pimenta ap\u00f3s seu consumo? Descubra aqui a melhor maneira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como neutralizar pimenta ap\u00f3s seu consumo? - Pimentoteca\" \/>\n<meta property=\"og:description\" content=\"Sua boca est\u00e1 em chamas? N\u00e3o sabe o que fazer? Quer descobrir como neutralizar pimenta ap\u00f3s seu consumo? Descubra aqui a melhor maneira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/\" \/>\n<meta property=\"og:site_name\" content=\"Pimentoteca\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-01T04:49:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T23:29:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2016\/11\/signo-capa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pimentoteca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pimentoteca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/\"},\"author\":{\"name\":\"Pimentoteca\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/5777d55d9ae544ec22036d5597d99873\"},\"headline\":\"Como neutralizar pimenta ap\u00f3s seu consumo?\",\"datePublished\":\"2019-02-01T04:49:48+00:00\",\"dateModified\":\"2026-07-13T23:29:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/5777d55d9ae544ec22036d5597d99873\"},\"image\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/signo-capa.jpg\",\"keywords\":[\"ardencia\",\"chamas\",\"como neutralizar\",\"gelo\",\"leite\",\"manteiga\",\"pimenta\",\"requeij\u00e3o\"],\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/\",\"url\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/\",\"name\":\"Como neutralizar pimenta ap\u00f3s seu consumo? - Pimentoteca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/signo-capa.jpg\",\"datePublished\":\"2019-02-01T04:49:48+00:00\",\"dateModified\":\"2026-07-13T23:29:11+00:00\",\"description\":\"Sua boca est\u00e1 em chamas? N\u00e3o sabe o que fazer? Quer descobrir como neutralizar pimenta ap\u00f3s seu consumo? Descubra aqui a melhor maneira!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/signo-capa.jpg\",\"contentUrl\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/signo-capa.jpg\",\"width\":680,\"height\":300,\"caption\":\"Como neutralizar pimenta?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/curiosidades\\\/como-neutralizar-pimenta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como neutralizar pimenta ap\u00f3s seu consumo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/\",\"name\":\"Pimentoteca\",\"description\":\"Pimentoteca: Explorando o Mundo das Pimentas\",\"publisher\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/5777d55d9ae544ec22036d5597d99873\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/5777d55d9ae544ec22036d5597d99873\",\"name\":\"Pimentoteca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/pimentoteca-logo-ico-1.png\",\"url\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/pimentoteca-logo-ico-1.png\",\"contentUrl\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/pimentoteca-logo-ico-1.png\",\"width\":512,\"height\":512,\"caption\":\"Pimentoteca\"},\"logo\":{\"@id\":\"https:\\\/\\\/pimentoteca.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/pimentoteca-logo-ico-1.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como neutralizar pimenta ap\u00f3s seu consumo? - Pimentoteca","description":"Sua boca est\u00e1 em chamas? N\u00e3o sabe o que fazer? Quer descobrir como neutralizar pimenta ap\u00f3s seu consumo? Descubra aqui a melhor maneira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/","og_locale":"pt_BR","og_type":"article","og_title":"Como neutralizar pimenta ap\u00f3s seu consumo? - Pimentoteca","og_description":"Sua boca est\u00e1 em chamas? N\u00e3o sabe o que fazer? Quer descobrir como neutralizar pimenta ap\u00f3s seu consumo? Descubra aqui a melhor maneira!","og_url":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/","og_site_name":"Pimentoteca","article_published_time":"2019-02-01T04:49:48+00:00","article_modified_time":"2026-07-13T23:29:11+00:00","og_image":[{"width":680,"height":300,"url":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2016\/11\/signo-capa.jpg","type":"image\/jpeg"}],"author":"Pimentoteca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pimentoteca","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#article","isPartOf":{"@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/"},"author":{"name":"Pimentoteca","@id":"https:\/\/pimentoteca.com.br\/blog\/#\/schema\/person\/5777d55d9ae544ec22036d5597d99873"},"headline":"Como neutralizar pimenta ap\u00f3s seu consumo?","datePublished":"2019-02-01T04:49:48+00:00","dateModified":"2026-07-13T23:29:11+00:00","mainEntityOfPage":{"@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/pimentoteca.com.br\/blog\/#\/schema\/person\/5777d55d9ae544ec22036d5597d99873"},"image":{"@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#primaryimage"},"thumbnailUrl":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2016\/11\/signo-capa.jpg","keywords":["ardencia","chamas","como neutralizar","gelo","leite","manteiga","pimenta","requeij\u00e3o"],"articleSection":["Curiosidades"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/","url":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/","name":"Como neutralizar pimenta ap\u00f3s seu consumo? - Pimentoteca","isPartOf":{"@id":"https:\/\/pimentoteca.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#primaryimage"},"image":{"@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#primaryimage"},"thumbnailUrl":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2016\/11\/signo-capa.jpg","datePublished":"2019-02-01T04:49:48+00:00","dateModified":"2026-07-13T23:29:11+00:00","description":"Sua boca est\u00e1 em chamas? N\u00e3o sabe o que fazer? Quer descobrir como neutralizar pimenta ap\u00f3s seu consumo? Descubra aqui a melhor maneira!","breadcrumb":{"@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#primaryimage","url":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2016\/11\/signo-capa.jpg","contentUrl":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2016\/11\/signo-capa.jpg","width":680,"height":300,"caption":"Como neutralizar pimenta?"},{"@type":"BreadcrumbList","@id":"https:\/\/pimentoteca.com.br\/blog\/curiosidades\/como-neutralizar-pimenta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/pimentoteca.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como neutralizar pimenta ap\u00f3s seu consumo?"}]},{"@type":"WebSite","@id":"https:\/\/pimentoteca.com.br\/blog\/#website","url":"https:\/\/pimentoteca.com.br\/blog\/","name":"Pimentoteca","description":"Pimentoteca: Explorando o Mundo das Pimentas","publisher":{"@id":"https:\/\/pimentoteca.com.br\/blog\/#\/schema\/person\/5777d55d9ae544ec22036d5597d99873"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pimentoteca.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/pimentoteca.com.br\/blog\/#\/schema\/person\/5777d55d9ae544ec22036d5597d99873","name":"Pimentoteca","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2018\/05\/pimentoteca-logo-ico-1.png","url":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2018\/05\/pimentoteca-logo-ico-1.png","contentUrl":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2018\/05\/pimentoteca-logo-ico-1.png","width":512,"height":512,"caption":"Pimentoteca"},"logo":{"@id":"https:\/\/pimentoteca.com.br\/blog\/wp-content\/uploads\/2018\/05\/pimentoteca-logo-ico-1.png"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/posts\/1818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1818"}],"version-history":[{"count":11,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/posts\/1818\/revisions"}],"predecessor-version":[{"id":3232,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/posts\/1818\/revisions\/3232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/media\/220"}],"wp:attachment":[{"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pimentoteca.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}